{"id":57,"date":"2019-04-13T10:29:56","date_gmt":"2019-04-13T09:29:56","guid":{"rendered":"https:\/\/abdoumoustoifa.wordpress.com\/?p=57"},"modified":"2019-04-13T10:29:56","modified_gmt":"2019-04-13T09:29:56","slug":"envois-de-fonds-en-afrique-la-diaspora-comorienne-a-contribue-a-hauteur-de-19-du-pib-national","status":"publish","type":"post","link":"https:\/\/abdoumoustoifa.info\/index.php\/2019\/04\/13\/envois-de-fonds-en-afrique-la-diaspora-comorienne-a-contribue-a-hauteur-de-19-du-pib-national\/","title":{"rendered":"Envois de fonds en Afrique\u00a0:  La Diaspora comorienne a contribu\u00e9 \u00e0 hauteur de 19% du Pib national"},"content":{"rendered":"<p><strong><em>En 2018, l\u2019Afrique subsaharienne, s\u2019est accapar\u00e9e, la plus importante part des fonds exp\u00e9di\u00e9s au continent depuis l\u2019ext\u00e9rieur, selon la derni\u00e8re note d\u2019information de la Banque mondiale, sur la migration, le d\u00e9veloppement et l\u2019envoi de fonds vers les pays \u00e0 revenu faible et interm\u00e9diaire, publi\u00e9e en d\u00e9but de semaine. Le seul b\u00e9mol, soulev\u00e9 dans ce rapport :\u00a0 les co\u00fbts \u00e9lev\u00e9s des frais d\u2019envoi. \u00a0Si en termes de volume les Comores ne figurent pas sur le podium, elles occupent par contre, la premi\u00e8re place, dans le classement des pays dont la diaspora a beaucoup contribu\u00e9 au Produit int\u00e9rieur brut annuel. <\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-58\" src=\"http:\/\/abdoumoustoifa.info\/wp-content\/uploads\/2020\/01\/cover_image.jpg.640x360_q85_crop.jpg\" alt=\"cover_image.jpg.640x360_q85_crop\" width=\"640\" height=\"360\" srcset=\"https:\/\/abdoumoustoifa.info\/wp-content\/uploads\/2020\/01\/cover_image.jpg.640x360_q85_crop.jpg 640w, https:\/\/abdoumoustoifa.info\/wp-content\/uploads\/2020\/01\/cover_image.jpg.640x360_q85_crop-300x169.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><strong>Par Abdou Moustoifa\u00a0<\/strong><\/p>\n<p>Les fonds envoy\u00e9s par la diaspora comorienne en 2018, repr\u00e9sentent 19% du produit int\u00e9rieur brut. Gr\u00e2ce \u00e0 ce taux (le plus \u00e9lev\u00e9 en Afrique), les Comores m\u00e8nent la danse sur cet aspect au niveau continental et occupent ainsi la premi\u00e8re place. Une contribution qui a beaucoup influ\u00e9 sur le Pib \u00e0 en croire un r\u00e9cent rapport de la Banque Mondiale.<\/p>\n<p>Dans ce top 5 des pays dont la diaspora a beaucoup apport\u00e9 sur cet indice qui d\u00e9termine la qualit\u00e9 de vie des citoyens du monde,\u00a0 les \u00eeles de la lune devancent, la Gambie (15.3%), le Lesotho cr\u00e9dit\u00e9 d\u2019un taux de 14.7% et le Cap-Vert qui a 12.3%. Le pays de George Weah, a cl\u00f4tur\u00e9 ce classement africain (12%), pendant que celui de son homologue capverdien, Jorge Carlos Fonseca (12.03%). Dans la r\u00e9gion, Moroni surclasse, ses voisins. Les devises envoy\u00e9s la Diaspora des pays comme le Kenya, ou encore Madagascar, n\u2019ont pas apport\u00e9 grand-chose sur les Pib. De l\u2019Oc\u00e9an indien, jusqu\u2019\u00e0 l\u2019Afrique de l\u2019Est, aucun pays n\u2019a atteint la barre des 10%.<\/p>\n<p>Cette note de la Banque Mondiale, rendue publique, le 8 avril, \u00e0 Washington, et accessible depuis le site officiel de l\u2019agence, montre que les fonds envoy\u00e9s vers les pays \u00e0 revenu fable et interm\u00e9diaire, durant l\u2019ann\u00e9e qui vient de s\u2019\u00e9couler, sont estim\u00e9s \u00e0 529 milliards de dollars. G\u00e9n\u00e9ralement, on a remarqu\u00e9 une dynamique en ce qui concerne les transferts d\u2019argent vers les patries d\u2019origine. Aucune r\u00e9gion n\u2019est en reste.<\/p>\n<p>Lire aussi : https:\/\/www.agenceecofin.com\/commerce\/0904-65266-les-envois-de-fonds-de-la-diaspora-vers-lafrique-subsaharienne-ont-grimpe-de-9-6-a-46-milliards-en-2018-banque-mondiale<\/p>\n<p><strong>143 millions de dollars en 2018<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Les auteurs de ce document que publie chaque ann\u00e9e, l\u2019institution de Bretton-Woods, l\u2019ann\u00e9e 2018 a enregistr\u00e9 une progression de 9.6% par rapport \u00e0 l\u2019ann\u00e9e derni\u00e8re. Les envois de fonds dans les pays \u00e0 revenu faible et interm\u00e9diaire, pourraient en 2019, atteindre 550 milliards de dollars au niveau mondial, ont r\u00e9v\u00e9l\u00e9 les pr\u00e9visions de la Banque Mondiale.<\/p>\n<p>Cet argent constituera dans un avenir proche, la principale source de financement ext\u00e9rieur pour les pays en voie de d\u00e9veloppement lit-on dans la fiche. De l\u2019Afrique du nord en passant par l\u2019Asie, le pacifique, jusqu\u2019en Afrique Subsaharienne les r\u00e9sultats sont encourageants. En Asie, l\u2019Inde reste en t\u00eate.<\/p>\n<p>La deuxi\u00e8me d\u00e9mographie du monde, a b\u00e9n\u00e9fici\u00e9 de 79 milliards de dollars. Elle est suivie par la Chine (67). Les pays qui se situent au sud du d\u00e9sert du Sahara, les envois de fonds sont pass\u00e9s de 42 \u00e0 46 milliards en un an. Le Nig\u00e9ria se taille la part du lion avec pr\u00e8s de 24.3 milliards. Au niveau de l\u2019Oc\u00e9an Indien, ce sont les Seychelles qui se hissent en premi\u00e8re place. Les Comores tablent sur, 143 millions de dollars (2018) selon le tableau de l\u2019institution.<\/p>\n<p>Pour p\u00e9renniser cette tendance, il est question de r\u00e9duire, les co\u00fbts li\u00e9s aux transferts d\u2019argent. En rediscutant avec les partenaires, pour que ceux-ci descendent jusqu\u2019\u00e0 3% d\u2019ici 2030, objectif, phare des Odd. Les donn\u00e9es disponibles de la Banque Mondiale, r\u00e9v\u00e8lent que ceux qui ont \u00e0 envoyer l\u2019argent pendant le premier trimestre de 2019, \u00e9taient oblig\u00e9s de supporter des frais d\u2019envoi de 7%.<\/p>\n<div id=\"wp-share-button-57\" class=\"wp-share-button theme20\"><span class=\"total-share \"><i class=\"total-count-text\">Total Share<\/i> <i class=\"total-count\">0<\/i> <\/span><a target=\"_blank\" href=\"mailto:?subject=Envois%20de%20fonds%20en%20Afrique\u00a0:%20%20La%20Diaspora%20comorienne%20a%20contribu\u00e9%20\u00e0%20hauteur%20de%2019%%20du%20Pib%20national&#038;body=https:\/\/abdoumoustoifa.info\/index.php\/2019\/04\/13\/envois-de-fonds-en-afrique-la-diaspora-comorienne-a-contribue-a-hauteur-de-19-du-pib-national\/\" class=\"share-button share-button-57 email\" id=\"email\" data-nonce=\"0fb59d74ad\">\r\n\r\n<span class=\"button-icon\">&lt;i class=&quot;far fa-envelope&quot;&gt;&lt;\/i&gt;<\/span>\r\n<span class=\"button-name\">Email<\/span>\r\n\r\n<span class=\"button-count\">0<\/span>\r\n\r\n<\/a>\r\n\r\n<a target=\"_blank\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/abdoumoustoifa.info\/index.php\/2019\/04\/13\/envois-de-fonds-en-afrique-la-diaspora-comorienne-a-contribue-a-hauteur-de-19-du-pib-national\/\" class=\"share-button share-button-57 facebook\" id=\"facebook\" data-nonce=\"0fb59d74ad\">\r\n\r\n<span class=\"button-icon\">&lt;i class=&quot;fab fa-facebook-f&quot;&gt;&lt;\/i&gt;<\/span>\r\n<span class=\"button-name\">Facebook<\/span>\r\n\r\n<span class=\"button-count\">0<\/span>\r\n\r\n<\/a>\r\n\r\n<a target=\"_blank\" href=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/abdoumoustoifa.info\/index.php\/2019\/04\/13\/envois-de-fonds-en-afrique-la-diaspora-comorienne-a-contribue-a-hauteur-de-19-du-pib-national\/&#038;text=Envois%20de%20fonds%20en%20Afrique\u00a0:%20%20La%20Diaspora%20comorienne%20a%20contribu\u00e9%20\u00e0%20hauteur%20de%2019%%20du%20Pib%20national\" class=\"share-button share-button-57 twitter\" id=\"twitter\" data-nonce=\"0fb59d74ad\">\r\n\r\n<span class=\"button-icon\">&lt;i class=&quot;fab fa-twitter&quot;&gt;&lt;\/i&gt;<\/span>\r\n<span class=\"button-name\">Twitter<\/span>\r\n\r\n<span class=\"button-count\">0<\/span>\r\n\r\n<\/a>\r\n\r\n<a target=\"_blank\" href=\"http:\/\/www.reddit.com\/submit?title=Envois%20de%20fonds%20en%20Afrique\u00a0:%20%20La%20Diaspora%20comorienne%20a%20contribu\u00e9%20\u00e0%20hauteur%20de%2019%%20du%20Pib%20national&#038;url=https:\/\/abdoumoustoifa.info\/index.php\/2019\/04\/13\/envois-de-fonds-en-afrique-la-diaspora-comorienne-a-contribue-a-hauteur-de-19-du-pib-national\/\" class=\"share-button share-button-57 reddit\" id=\"reddit\" data-nonce=\"0fb59d74ad\">\r\n\r\n<span class=\"button-icon\">&lt;i class=&quot;fab fa-reddit-alien&quot;&gt;&lt;\/i&gt;<\/span>\r\n<span class=\"button-name\">Reddit<\/span>\r\n\r\n<span class=\"button-count\">0<\/span>\r\n\r\n<\/a>\r\n\r\n<a title=\"More...\" href=\"#wp-share-button-57\" class=\"share-button-more\"><span class=\"button-icon\"><i class=\"fa fa-plus\"><\/i><\/span><\/a><div class=\"wp-share-button-popup wp-share-button-popup-57\"><div class=\"popup-buttons\"><span class=\"close\">X<\/span><a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/shareArticle?url=https:\/\/abdoumoustoifa.info\/index.php\/2019\/04\/13\/envois-de-fonds-en-afrique-la-diaspora-comorienne-a-contribue-a-hauteur-de-19-du-pib-national\/&#038;title=Envois%20de%20fonds%20en%20Afrique\u00a0:%20%20La%20Diaspora%20comorienne%20a%20contribu\u00e9%20\u00e0%20hauteur%20de%2019%%20du%20Pib%20national&#038;summary=&#038;source=\" class=\"share-button share-button-57 linkedin\" id=\"linkedin\">\r\n\r\n<span class=\"button-icon\"><i class=\"fab fa-linkedin-in\"><\/i><\/span>\r\n<span class=\"button-name\">Linkedin<\/span>\r\n<span class=\"button-count\">0<\/span>\t\t\t\t\r\n\r\n<\/a>\r\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=https:\/\/abdoumoustoifa.info\/index.php\/2019\/04\/13\/envois-de-fonds-en-afrique-la-diaspora-comorienne-a-contribue-a-hauteur-de-19-du-pib-national\/&#038;title=Envois%20de%20fonds%20en%20Afrique\u00a0:%20%20La%20Diaspora%20comorienne%20a%20contribu\u00e9%20\u00e0%20hauteur%20de%2019%%20du%20Pib%20national\" class=\"share-button share-button-57 stumbleupon\" id=\"stumbleupon\">\r\n\r\n<span class=\"button-icon\"><i class=\"fab fa-stumbleupon\"><\/i><\/span>\r\n<span class=\"button-name\">Stumbleupon<\/span>\r\n<span class=\"button-count\">0<\/span>\t\t\t\t\r\n\r\n<\/a>\r\n<\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>En 2018, l\u2019Afrique subsaharienne, s\u2019est accapar\u00e9e, la plus importante part des fonds exp\u00e9di\u00e9s au continent depuis l\u2019ext\u00e9rieur, selon la derni\u00e8re note d\u2019information de la Banque mondiale, sur la migration, le d\u00e9veloppement et l\u2019envoi de fonds vers les pays \u00e0 revenu faible et interm\u00e9diaire, publi\u00e9e en d\u00e9but de semaine. Le seul b\u00e9mol, soulev\u00e9 dans ce rapport&hellip; <a class=\"more-link\" href=\"https:\/\/abdoumoustoifa.info\/index.php\/2019\/04\/13\/envois-de-fonds-en-afrique-la-diaspora-comorienne-a-contribue-a-hauteur-de-19-du-pib-national\/\">Poursuivre la lecture <span class=\"screen-reader-text\">Envois de fonds en Afrique\u00a0:  La Diaspora comorienne a contribu\u00e9 \u00e0 hauteur de 19% du Pib national<\/span><\/a><\/p>\n<div id=\"wp-share-button-57\" class=\"wp-share-button theme20\"><span class=\"total-share \"><i class=\"total-count-text\">Total Share<\/i> <i class=\"total-count\">0<\/i> <\/span><a target=\"_blank\" href=\"mailto:?subject=Envois%20de%20fonds%20en%20Afrique\u00a0:%20%20La%20Diaspora%20comorienne%20a%20contribu\u00e9%20\u00e0%20hauteur%20de%2019%%20du%20Pib%20national&#038;body=https:\/\/abdoumoustoifa.info\/index.php\/2019\/04\/13\/envois-de-fonds-en-afrique-la-diaspora-comorienne-a-contribue-a-hauteur-de-19-du-pib-national\/\" class=\"share-button share-button-57 email\" id=\"email\" data-nonce=\"0fb59d74ad\">\r\n\r\n<span class=\"button-icon\">&lt;i class=&quot;far fa-envelope&quot;&gt;&lt;\/i&gt;<\/span>\r\n<span class=\"button-name\">Email<\/span>\r\n\r\n<span class=\"button-count\">0<\/span>\r\n\r\n<\/a>\r\n\r\n<a target=\"_blank\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/abdoumoustoifa.info\/index.php\/2019\/04\/13\/envois-de-fonds-en-afrique-la-diaspora-comorienne-a-contribue-a-hauteur-de-19-du-pib-national\/\" class=\"share-button share-button-57 facebook\" id=\"facebook\" data-nonce=\"0fb59d74ad\">\r\n\r\n<span class=\"button-icon\">&lt;i class=&quot;fab fa-facebook-f&quot;&gt;&lt;\/i&gt;<\/span>\r\n<span class=\"button-name\">Facebook<\/span>\r\n\r\n<span class=\"button-count\">0<\/span>\r\n\r\n<\/a>\r\n\r\n<a target=\"_blank\" href=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/abdoumoustoifa.info\/index.php\/2019\/04\/13\/envois-de-fonds-en-afrique-la-diaspora-comorienne-a-contribue-a-hauteur-de-19-du-pib-national\/&#038;text=Envois%20de%20fonds%20en%20Afrique\u00a0:%20%20La%20Diaspora%20comorienne%20a%20contribu\u00e9%20\u00e0%20hauteur%20de%2019%%20du%20Pib%20national\" class=\"share-button share-button-57 twitter\" id=\"twitter\" data-nonce=\"0fb59d74ad\">\r\n\r\n<span class=\"button-icon\">&lt;i class=&quot;fab fa-twitter&quot;&gt;&lt;\/i&gt;<\/span>\r\n<span class=\"button-name\">Twitter<\/span>\r\n\r\n<span class=\"button-count\">0<\/span>\r\n\r\n<\/a>\r\n\r\n<a target=\"_blank\" href=\"http:\/\/www.reddit.com\/submit?title=Envois%20de%20fonds%20en%20Afrique\u00a0:%20%20La%20Diaspora%20comorienne%20a%20contribu\u00e9%20\u00e0%20hauteur%20de%2019%%20du%20Pib%20national&#038;url=https:\/\/abdoumoustoifa.info\/index.php\/2019\/04\/13\/envois-de-fonds-en-afrique-la-diaspora-comorienne-a-contribue-a-hauteur-de-19-du-pib-national\/\" class=\"share-button share-button-57 reddit\" id=\"reddit\" data-nonce=\"0fb59d74ad\">\r\n\r\n<span class=\"button-icon\">&lt;i class=&quot;fab fa-reddit-alien&quot;&gt;&lt;\/i&gt;<\/span>\r\n<span class=\"button-name\">Reddit<\/span>\r\n\r\n<span class=\"button-count\">0<\/span>\r\n\r\n<\/a>\r\n\r\n<a title=\"More...\" href=\"#wp-share-button-57\" class=\"share-button-more\"><span class=\"button-icon\"><i class=\"fa fa-plus\"><\/i><\/span><\/a><div class=\"wp-share-button-popup wp-share-button-popup-57\"><div class=\"popup-buttons\"><span class=\"close\">X<\/span><a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/shareArticle?url=https:\/\/abdoumoustoifa.info\/index.php\/2019\/04\/13\/envois-de-fonds-en-afrique-la-diaspora-comorienne-a-contribue-a-hauteur-de-19-du-pib-national\/&#038;title=Envois%20de%20fonds%20en%20Afrique\u00a0:%20%20La%20Diaspora%20comorienne%20a%20contribu\u00e9%20\u00e0%20hauteur%20de%2019%%20du%20Pib%20national&#038;summary=&#038;source=\" class=\"share-button share-button-57 linkedin\" id=\"linkedin\">\r\n\r\n<span class=\"button-icon\"><i class=\"fab fa-linkedin-in\"><\/i><\/span>\r\n<span class=\"button-name\">Linkedin<\/span>\r\n<span class=\"button-count\">0<\/span>\t\t\t\t\r\n\r\n<\/a>\r\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=https:\/\/abdoumoustoifa.info\/index.php\/2019\/04\/13\/envois-de-fonds-en-afrique-la-diaspora-comorienne-a-contribue-a-hauteur-de-19-du-pib-national\/&#038;title=Envois%20de%20fonds%20en%20Afrique\u00a0:%20%20La%20Diaspora%20comorienne%20a%20contribu\u00e9%20\u00e0%20hauteur%20de%2019%%20du%20Pib%20national\" class=\"share-button share-button-57 stumbleupon\" id=\"stumbleupon\">\r\n\r\n<span class=\"button-icon\"><i class=\"fab fa-stumbleupon\"><\/i><\/span>\r\n<span class=\"button-name\">Stumbleupon<\/span>\r\n<span class=\"button-count\">0<\/span>\t\t\t\t\r\n\r\n<\/a>\r\n<\/div><\/div><\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-57","post","type-post","status-publish","format-standard","hentry","category-finances","entry"],"_links":{"self":[{"href":"https:\/\/abdoumoustoifa.info\/index.php\/wp-json\/wp\/v2\/posts\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abdoumoustoifa.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abdoumoustoifa.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abdoumoustoifa.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/abdoumoustoifa.info\/index.php\/wp-json\/wp\/v2\/comments?post=57"}],"version-history":[{"count":0,"href":"https:\/\/abdoumoustoifa.info\/index.php\/wp-json\/wp\/v2\/posts\/57\/revisions"}],"wp:attachment":[{"href":"https:\/\/abdoumoustoifa.info\/index.php\/wp-json\/wp\/v2\/media?parent=57"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abdoumoustoifa.info\/index.php\/wp-json\/wp\/v2\/categories?post=57"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abdoumoustoifa.info\/index.php\/wp-json\/wp\/v2\/tags?post=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}